{"id":21628,"date":"2019-03-11T17:35:14","date_gmt":"2019-03-11T17:35:14","guid":{"rendered":"https:\/\/www.mijas.es\/portal\/?p=21628"},"modified":"2019-05-13T14:34:33","modified_gmt":"2019-05-13T14:34:33","slug":"maldonado-erradica-la-tasa-de-basura-para-todos-los-mijenos","status":"publish","type":"post","link":"https:\/\/www.mijas.es\/portal\/maldonado-erradica-la-tasa-de-basura-para-todos-los-mijenos\/","title":{"rendered":"Maldonado erradica la tasa de basura para todos los mije\u00f1os"},"content":{"rendered":"\n<p>Los vecinos dejar\u00e1n de pagar el tributo a partir de 2020 lo que va a suponer una merma del presupuesto de 6 millones de euros que el gobierno municipal puede afrontar gracias a la deuda cero y los 100 millones de euros de super\u00e1vit<\/p>\n\n\n\n<p>Esta medida se suma a la bajada de impuestos que entr\u00f3 en vigor en 2018 (IBI, Plusval\u00eda, IVTM y expedici\u00f3n de documentos) que pone en el bolsillo de los residentes otros 5 millones de euros as\u00ed como a la tasa cero del deporte que significa otros 800.000 euros m\u00e1s de ahorro para las familias de la ciudad<\/p>\n\n\n\n<p><strong>Mijas, 11 de marzo de 2019.-<\/strong>&nbsp;El alcalde de Mijas, Juan Carlos Maldonado y el edil de Recogida de Residuos S\u00f3lidos, Jos\u00e9 Carlos Mart\u00edn, han anunciado esta ma\u00f1ana que el gobierno municipal ha comenzado los tr\u00e1mites para erradicar la tasa de basura en la ciudad. La medida entrar\u00e1 en vigor para el ejercicio 2020 y viene a sumarse a todas las actuaciones puestas en marcha desde el Ayuntamiento para aliviar las cargas fiscales a los ciudadanos. \u201cGracias a la gesti\u00f3n responsable que hemos estado llevando a cabo desde que entr\u00e9 a la alcald\u00eda vamos a poner en el bolsillo de los vecinos cerca de 12 millones de euros anualmente. Una cifra importante de ahorro para todos los hogares de la ciudad\u201d, se\u00f1ala el regidor.<\/p>\n\n\n\n<p>Este nuevo avance va a suponer una merma&nbsp;del presupuesto de 6 millones de euros que el gobierno municipal puede afrontar gracias a la deuda cero y los 100 millones de euros de super\u00e1vit. \u201cHay que revertir el esfuerzo que este equipo de gobierno est\u00e1 haciendo en el bienestar de los vecinos. Por un lado con todas estas iniciativas fiscales que les benefician y, por otro, con todos los servicios e infraestructuras que estamos ejecutando gracias al buen uso del dinero p\u00fablico que hemos llevado a cabo en estos \u00faltimos cuatro a\u00f1os\u201d, a\u00f1ade Maldonado.<\/p>\n\n\n\n<p>La primera bajada de impuestos en la historia de Mijas ha estado capitaneada por el alcalde, Juan Carlos Maldonado, consiguiendo, en una primera actuaci\u00f3n, reducir en un 5 por ciento el IBI y la Plusval\u00eda. En lo que respecta al impuesto de circulaci\u00f3n (IVTM), el Ayuntamiento bonifica a los conductores que tengan veh\u00edculos el\u00e9ctricos o a gas y, en tal caso, se subvenciona entre un 50 y un 70 por ciento el total del tributo. Adem\u00e1s se han reducido las tasas por documentos que se expiden desde el Consistorio. Esta medida entr\u00f3 en vigor en enero de 2018 y pone en el bolsillo de todos los mije\u00f1os 5 millones de euros anuales.<\/p>\n\n\n\n<p>En enero de 2019 se hac\u00eda efectivo otro de los grandes logros del gobierno de Maldonado: las actividades deportivas ya son gratis en Mijas. Esta decisi\u00f3n afecta a los m\u00e1s de 6.000 usuarios del municipio y supone un ahorro para todas estas familias de 800.000 euros al a\u00f1o.<\/p>\n\n\n\n<p>Con esta nueva medida anunciada hoy, el equipo de gobierno demuestra que ha cumplido sus compromisos a lo largo de la legislatura y pone el broche de oro a una l\u00ednea de actuaci\u00f3n de la cual pocos municipios de Espa\u00f1a pueden presumir como lo hace Mijas.<\/p>\n\n\n\n<p><strong>El gran ahorro de la recogida de basura<\/strong><\/p>\n\n\n\n<p>Por su parte, Mart\u00edn ha destacado otro de los grandes hitos conseguidos por el gobierno municipal como ha sido el hecho de sacar a licitaci\u00f3n p\u00fablica tras 40 a\u00f1os sin contrato el servicio de recogida de basura en la ciudad. \u201cLas arcas municipales se ahorran cada a\u00f1o un mill\u00f3n de euros gracias a esta iniciativa y, adem\u00e1s, hemos implementado el servicio. Una actuaci\u00f3n que vamos a repetir en breve con la prestaci\u00f3n por limpieza viaria que se encuentra en las mismas condiciones. A fin de cuentas se trata de una buena gesti\u00f3n del dinero p\u00fablico respetando todos los procedimientos administrativos que revierte en actuaciones como la que hoy anunciamos: bajada de impuestos y erradicaci\u00f3n de tasas\u201d, apunta el concejal.<\/p>\n\n\n\n<p>As\u00ed pues, el contrato de basura ha permitido que se duplique la flota de veh\u00edculos pasando de 15 a 31 adem\u00e1s de poner en marcha otros servicios como el punto limpio m\u00f3vil o la instalaci\u00f3n de localizadores para ir siguiendo las rutas de los camiones en tiempo real. Tambi\u00e9n se han colocado dispositivos en los contenedores para que den un aviso cuando bosen y se han desarrollado campa\u00f1as de concienciaci\u00f3n y sensibilizaci\u00f3n buscando la complicidad de la ciudadan\u00eda a la hora de mantener la localidad limpia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los vecinos dejar\u00e1n de pagar el tributo a partir de 2020 lo que va a suponer una merma del presupuesto de 6 millones de euros que el gobierno municipal puede afrontar gracias a la deuda cero y los 100 millones de euros de super\u00e1vit Esta medida se suma a la bajada de impuestos que entr\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"jetpack_featured_media_url":"https:\/\/www.mijas.es\/wp-content\/uploads\/2019\/05\/20190311_Tasa_cero_basura.jpg","_links":{"self":[{"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/posts\/21628"}],"collection":[{"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/comments?post=21628"}],"version-history":[{"count":1,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/posts\/21628\/revisions"}],"predecessor-version":[{"id":21629,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/posts\/21628\/revisions\/21629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/media\/21630"}],"wp:attachment":[{"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/media?parent=21628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/categories?post=21628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mijas.es\/portal\/wp-json\/wp\/v2\/tags?post=21628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}